{"id":934,"count":1,"description":"","link":"https:\/\/mymoleskine.moleskine.com\/community\/tag\/atene-tschumi-museum-atena-athena-nike-alata-vittoria-il_bruno\/","name":"atene tschumi museum atena athena nike alata vittoria il_bruno","slug":"atene-tschumi-museum-atena-athena-nike-alata-vittoria-il_bruno","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v15.2.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>atene tschumi museum atena athena nike alata vittoria il_bruno Archives - myMoleskine Community<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mymoleskine.moleskine.com\/community\/tag\/atene-tschumi-museum-atena-athena-nike-alata-vittoria-il_bruno\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"atene tschumi museum atena athena nike alata vittoria il_bruno Archives - myMoleskine Community\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mymoleskine.moleskine.com\/community\/tag\/atene-tschumi-museum-atena-athena-nike-alata-vittoria-il_bruno\/\" \/>\n<meta property=\"og:site_name\" content=\"myMoleskine Community\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/mymoleskine.moleskine.com\/community\/#website\",\"url\":\"https:\/\/mymoleskine.moleskine.com\/community\/\",\"name\":\"myMoleskine Community\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/mymoleskine.moleskine.com\/community\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/mymoleskine.moleskine.com\/community\/tag\/atene-tschumi-museum-atena-athena-nike-alata-vittoria-il_bruno\/#webpage\",\"url\":\"https:\/\/mymoleskine.moleskine.com\/community\/tag\/atene-tschumi-museum-atena-athena-nike-alata-vittoria-il_bruno\/\",\"name\":\"atene tschumi museum atena athena nike alata vittoria il_bruno Archives - myMoleskine Community\",\"isPartOf\":{\"@id\":\"https:\/\/mymoleskine.moleskine.com\/community\/#website\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/mymoleskine.moleskine.com\/community\/tag\/atene-tschumi-museum-atena-athena-nike-alata-vittoria-il_bruno\/\"]}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/mymoleskine.moleskine.com\/community\/wp-json\/wp\/v2\/tags\/934"}],"collection":[{"href":"https:\/\/mymoleskine.moleskine.com\/community\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/mymoleskine.moleskine.com\/community\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/mymoleskine.moleskine.com\/community\/wp-json\/wp\/v2\/posts?tags=934"},{"href":"https:\/\/mymoleskine.moleskine.com\/community\/wp-json\/wp\/v2\/msk?tags=934"},{"href":"https:\/\/mymoleskine.moleskine.com\/community\/wp-json\/wp\/v2\/hacks?tags=934"},{"href":"https:\/\/mymoleskine.moleskine.com\/community\/wp-json\/wp\/v2\/photos?tags=934"},{"href":"https:\/\/mymoleskine.moleskine.com\/community\/wp-json\/wp\/v2\/myanalogcloud?tags=934"},{"href":"https:\/\/mymoleskine.moleskine.com\/community\/wp-json\/wp\/v2\/moleskinejournal?tags=934"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}